{"id":2993,"date":"2019-01-24T16:27:19","date_gmt":"2019-01-24T18:27:19","guid":{"rendered":"https:\/\/valorhconsultoria.com.br\/?p=2993"},"modified":"2020-05-20T19:40:59","modified_gmt":"2020-05-20T22:40:59","slug":"definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional","status":"publish","type":"post","link":"https:\/\/pt.valorhconsultoria.com\/pt\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/","title":{"rendered":"Definir metas \u00e9 um componente fundamental para o sucesso profissional"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2019\/01\/METAS-1.jpg\" alt=\"\" width=\"1080\" height=\"716\"><\/p>\n\n\n<h2>Veja dicas para manter em mente quando voc\u00ea pensar em propor metas, quer sejam elas pessoais ou corporativas<\/h2>\n<p><span style=\"font-weight: 400;\">Definir metas \u00e9 um componente fundamental para o sucesso profissional, no longo prazo. A raz\u00e3o b\u00e1sica para isto \u00e9 que ningu\u00e9m pode chegar onde pretende sem, antes, definir claramente onde \u00e9 este lugar. <\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Metas nos ajudam a nos concentrarmos\u00a0e a\u00a0 alocarmos o nosso tempo e recursos de forma eficiente. Elas tamb\u00e9m tem o efeito de nos manter motivados quando sentimos vontade de desistir.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">No \u00e2mbito das equipes, as metas deixam claro para\u00a0os funcion\u00e1rios o que \u00e9 esperado deles, restando pouco espa\u00e7o para as pessoas se esconderem por tr\u00e1s da cortina de expectativas n\u00e3o especificadas. Ou seja, elas possibilitam que as pessoas sejam cobradas por algo que sabiam que teriam que fazer. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas o melhor, \u00e9 que quando s\u00e3o alcan\u00e7ados, os resultados se traduzem em um sentimento de sucesso coletivo que, por sua vez, cria um clima de mais motiva\u00e7\u00e3o e produtividade.<\/span><\/p>\n<h4><span style=\"font-weight: 400;\">Aqui est\u00e3o algumas orienta\u00e7\u00f5es \u00fateis\u00a0para manter em mente quando voc\u00ea pensar em propor metas, quer sejam elas pessoais ou corporativas:<\/span><\/h4>\n<p><b>1 .<\/b><span style=\"font-weight: 400;\">\u00a0Certifique-se de que s\u00e3o vi\u00e1veis e espec\u00edficas. Voc\u00ea deve ser capaz de visualizar e\u00a0 compreender o resultado que espera obter. Os atletas usam a visualiza\u00e7\u00e3o para ajud\u00e1-los a alcan\u00e7ar o sucesso. Ao visualizar o seu sucesso com muita aten\u00e7\u00e3o aos detalhes, voc\u00ea est\u00e1 preparando-se e certificando-se de dar os passos necess\u00e1rios para chegar l\u00e1. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 de muito pouca utilidade definir como meta a aprova\u00e7\u00e3o no vestibular. Em que curso? Qualquer curso? Qual o ganho que se obt\u00e9m com esse tipo de resultado? Ao definir esse tipo de meta, determine qual a carreira que lhe interessa e, ent\u00e3o, foque suas energias nesta dire\u00e7\u00e3o. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quanto \u00e0 viabilidade, tamb\u00e9m ser\u00e1 igualmente in\u00fatil mirar em um curso muito concorrido, se voc\u00ea n\u00e3o est\u00e1 preparado para a concorr\u00eancia. Fa\u00e7a uma an\u00e1lise de suas possibilidades e mire em um objetivo poss\u00edvel.<\/span><\/p>\n<p><b>2 .<\/b><span style=\"font-weight: 400;\">\u00a0Certifique-se de que o objetivo \u00e9 mensur\u00e1vel. Tentar alcan\u00e7ar um sentimento (como ser feliz) ou uma realiza\u00e7\u00e3o amb\u00edgua n\u00e3o lhe possibilitar\u00e1 nenhuma maneira de medir o seu sucesso. Sempre que poss\u00edvel, tente quantificar os resultados que voc\u00ea est\u00e1 esperando, em percentuais, recursos financeiros ou tempo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isso permitir\u00e1 que voc\u00ea me\u00e7a o que voc\u00ea conseguiu e reajuste suas metas, caso necess\u00e1rio. Como exemplo, cito o caso das pessoas que se auto-determinam a meta de emagrecer. Quantos quilos? Em quanto tempo? De nada adianta apenas querer entrar naquela roupa, n\u00e3o \u00e9 mesmo?<\/span><\/p>\n<p><b>3 .<\/b><span style=\"font-weight: 400;\">\u00a0Certifique-se de que o objetivo est\u00e1 em suas m\u00e3os . Isto significa que voc\u00ea deve ser capaz de atingir a meta , como resultado de seu pr\u00f3prio trabalho duro e determina\u00e7\u00e3o, ou com a ajuda volunt\u00e1ria de algu\u00e9m que j\u00e1 faz parte de sua rede. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea n\u00e3o tem nenhum controle sobre o resultado, n\u00e3o se comprometa.\u00a0 Ent\u00e3o, nada de garantir que os \u201coutros\u201d far\u00e3o alguma coisa.<\/span><\/p>\n<p><b>4 .<\/b><span style=\"font-weight: 400;\">\u00a0Certifique-se de que as metas fa\u00e7am sentido em conjunto, sejam complementares. E a\u00ed vai um cl\u00e1ssico exemplo da administra\u00e7\u00e3o: n\u00e3o podemos querer aumentar a lucratividade e o volume de vendas ao mesmo tempo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">No plano pessoal, seria o mesmo que desejar aprova\u00e7\u00e3o em um concurso concorrido ao mesmo tempo em que se pretenda maior dedica\u00e7\u00e3o \u00e0 fam\u00edlia. Em ambos os casos, uma meta exclui a outra.<\/span><\/p>\n<p><b>5 .<\/b><span style=\"font-weight: 400;\">\u00a0N\u00e3o superestime a sua capacidade. Temos que admitir que algumas metas s\u00e3o de longo prazo, mesmo que queiramos muito atingi-las. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Saber dimensionar o quanto conseguimos nos aproximar dela, em cada per\u00edodo de planejamento,\u00a0 \u00e9 uma qualidade admirada.\u00a0 Tentar \u201cfor\u00e7ar a barra\u201d pode ser estressante para voc\u00ea e para sua equipe.<\/span><\/p>\n<p><b>6 .<\/b><span style=\"font-weight: 400;\">\u00a0Seja flex\u00edvel.\u00a0 Avalie o seu progresso periodicamente e, se necess\u00e1rio ajuste o seu plano de a\u00e7\u00e3o. Afinal, pode ser que voc\u00ea encontre\u00a0 obst\u00e1culos em seu caminho para alcan\u00e7ar seus objetivos, mas n\u00e3o desista. Em vez disso, esteja disposto a alter\u00e1-los para atender \u00e0s suas novas necessidades. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o se torne r\u00edgido no cumprimento de algo que n\u00e3o \u00e9 mais relevante para voc\u00ea ou sua empresa apenas porque consta do planejamento original ou se transformou em um capricho pessoal, uma quest\u00e3o de honra. \u00c0s vezes saber quando desistir ou mudar de marcha \u00e9 muito importante.<\/span><\/p>\n<p><b>7 .<\/b><span style=\"font-weight: 400;\">\u00a0Hierarquize as metas por seus prazos. As metas de longo prazo devem ser subdivididas em metas de m\u00e9dio e curto prazo. O\u00a0 longo prazo pode levar cerca de tr\u00eas a cinco anos para alcan\u00e7ar , enquanto que metas de curto prazo podem levar de alguns meses a um ano ou dois. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">A coisa funcionaria assim:\u00a0 vamos supor que voc\u00ea pretenda se transformar em um maratonista. A depender do seu preparo f\u00edsico atual essa pode ser uma meta de longo prazo. Antes de alcan\u00e7\u00e1-la, entretanto, voc\u00ea ter\u00e1 que fixar alvos mais pr\u00f3ximos, ou seja, come\u00e7ar a andar, come\u00e7ar a correr e, depois, paulatinamente, correr dist\u00e2ncias cada vez maiores at\u00e9 atingir os 42 km. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tenha cuidado, entretanto, para n\u00e3o se descuidar neste processo e transformar o seu longo prazo em dez anos. A disciplina \u00e9 fundamental!<\/span><\/p>\n<p><b>8 .<\/b><span style=\"font-weight: 400;\">\u00a0Certifique-se do que voc\u00ea realmente quer. As metas devem ser emocionalmente gratificantes.\u00a0 Certificar-se de que voc\u00ea realmente quer alcan\u00e7ar os objetivos que voc\u00ea definiu vai fazer voc\u00ea se esfor\u00e7ar mais quando a estrada ficar dif\u00edcil. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como um empregador voc\u00ea pode motivar a sua equipe adicionando incentivos que s\u00e3o pessoalmente significativos para seus empregados. Para tornar-se comprometido com uma meta, \u00e9 preciso acreditar em sua import\u00e2ncia ou significado.<\/span><\/p>\n<p><b>9 .<\/b><span style=\"font-weight: 400;\">\u00a0Anotar. Uma meta escrita representa um compromisso real . Compromisso \u00e9 o que separa os nossos sonhos de nossos objetivos. Mantenha uma c\u00f3pia de seu plano de meta \u00e0 vista e se refira a ele com frequ\u00eancia. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pesquisadores da Harvard Business School estudaram o que fez a diferen\u00e7a no sucesso ou fracasso para pessoas de origens e padr\u00f5es educacionais semelhantes. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seus estudos descobriram que\u00a0 apenas 3% dos entrevistados\u00a0 foram bem sucedidos e o que os ajudou\u00a0 \u00e9 que eles escreveram metas espec\u00edficas quanto ao que desejavam. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">O segredo por tr\u00e1s da iniciativa \u00e9 o desenvolvimento de h\u00e1bitos e estrat\u00e9gias de apoio ao cumprimento de metas claras .<\/span><\/p>\n<p><b>10 .<\/b><span style=\"font-weight: 400;\">\u00a0Definir as metas em conjunto. A fim de aumentar a motiva\u00e7\u00e3o, os funcion\u00e1rios precisam ser autorizados a participar do processo de defini\u00e7\u00e3o de metas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> \u00c9 por isso que \u00e9 importante mostrar aos funcion\u00e1rios como o seu objetivo particular contribui para o sucesso da organiza\u00e7\u00e3o. O truque \u00e9 conseguir um equil\u00edbrio entre dar aos funcion\u00e1rios a liberdade para decidir sobre suas metas e direcion\u00e1-los a cada passo do caminho.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por fim, reconhe\u00e7a o desempenho e os ganhos obtidos e comemore muito o alcance dos resultados. As metas ir\u00e3o mant\u00ea-lo em seu melhor desempenho e devem ser uma parte consistente da sua rotina pessoal ou empresarial. Pense nisso!\u00a0<\/span><\/p>\n<p style=\"font-weight: 400;\">Profa. Dra. Carolina Spinola<\/p>\n<p style=\"font-weight: 400;\">Consultora da \u00c1rea de Neg\u00f3cios da ValorH Consultoria e Professora Universit\u00e1ria. Administradora, Mestre em Administra\u00e7\u00e3o e Doutora em Geografia, com \u00eanfase em Desenvolvimento Regional<\/p>","protected":false},"excerpt":{"rendered":"<p>Veja dicas para manter em mente quando voc\u00ea pensar em propor metas, quer sejam elas pessoais ou corporativas Definir metas \u00e9 um componente fundamental para o sucesso profissional, no longo prazo. A raz\u00e3o b\u00e1sica para isto \u00e9 que ningu\u00e9m pode chegar onde pretende sem, antes, definir claramente onde \u00e9 este lugar. Metas nos ajudam a [&hellip;]<\/p>","protected":false},"author":3,"featured_media":2996,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[368,370,371,372,369],"class_list":["post-2993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-definir-metas","tag-metas","tag-metas-pessoais-e-corporativas","tag-motivacao","tag-sucesso-profissional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Definir metas \u00e9 um componente fundamental para o sucesso profissional<\/title>\n<meta name=\"description\" content=\"Veja dicas para manter em mente quando voc\u00ea pensar em propor metas, quer sejam elas pessoais ou corporativas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pt.valorhconsultoria.com\/pt\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Definir metas \u00e9 um componente fundamental para o sucesso profissional\" \/>\n<meta property=\"og:description\" content=\"Veja dicas para manter em mente quando voc\u00ea pensar em propor metas, quer sejam elas pessoais ou corporativas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pt.valorhconsultoria.com\/pt\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/\" \/>\n<meta property=\"og:site_name\" content=\"ValorH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/valorhconsultoria\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-24T18:27:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-20T22:40:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2019\/01\/METAS-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"716\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"valorh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"valorh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/\"},\"author\":{\"name\":\"valorh\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/person\\\/53caa52db0debe9896f35cf99abc3339\"},\"headline\":\"Definir metas \u00e9 um componente fundamental para o sucesso profissional\",\"datePublished\":\"2019-01-24T18:27:19+00:00\",\"dateModified\":\"2020-05-20T22:40:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/\"},\"wordCount\":1214,\"publisher\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/METAS-1.jpg\",\"keywords\":[\"Definir metas\",\"metas\",\"metas pessoais e corporativas\",\"motiva\u00e7\u00e3o\",\"sucesso profissional\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/\",\"name\":\"Definir metas \u00e9 um componente fundamental para o sucesso profissional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/METAS-1.jpg\",\"datePublished\":\"2019-01-24T18:27:19+00:00\",\"dateModified\":\"2020-05-20T22:40:59+00:00\",\"description\":\"Veja dicas para manter em mente quando voc\u00ea pensar em propor metas, quer sejam elas pessoais ou corporativas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/METAS-1.jpg\",\"contentUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/METAS-1.jpg\",\"width\":1080,\"height\":716},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Definir metas \u00e9 um componente fundamental para o sucesso profissional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#website\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\",\"name\":\"ValorH\",\"description\":\"Consultoria e Treinamento\",\"publisher\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\",\"name\":\"ValorH Consultoria e Treinamento\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/favicon.png\",\"width\":200,\"height\":199,\"caption\":\"ValorH Consultoria e Treinamento\"},\"image\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/valorhconsultoria\\\/\",\"https:\\\/\\\/www.instagram.com\\\/valorhconsultoria\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/in\\\/valorhconsultoria\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/person\\\/53caa52db0debe9896f35cf99abc3339\",\"name\":\"valorh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g\",\"caption\":\"valorh\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Definir metas \u00e9 um componente fundamental para o sucesso profissional","description":"Veja dicas para manter em mente quando voc\u00ea pensar em propor metas, quer sejam elas pessoais ou corporativas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pt.valorhconsultoria.com\/pt\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/","og_locale":"pt_PT","og_type":"article","og_title":"Definir metas \u00e9 um componente fundamental para o sucesso profissional","og_description":"Veja dicas para manter em mente quando voc\u00ea pensar em propor metas, quer sejam elas pessoais ou corporativas","og_url":"https:\/\/pt.valorhconsultoria.com\/pt\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/","og_site_name":"ValorH","article_publisher":"https:\/\/www.facebook.com\/valorhconsultoria\/","article_published_time":"2019-01-24T18:27:19+00:00","article_modified_time":"2020-05-20T22:40:59+00:00","og_image":[{"width":1080,"height":716,"url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2019\/01\/METAS-1.jpg","type":"image\/jpeg"}],"author":"valorh","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"valorh","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/#article","isPartOf":{"@id":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/"},"author":{"name":"valorh","@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/person\/53caa52db0debe9896f35cf99abc3339"},"headline":"Definir metas \u00e9 um componente fundamental para o sucesso profissional","datePublished":"2019-01-24T18:27:19+00:00","dateModified":"2020-05-20T22:40:59+00:00","mainEntityOfPage":{"@id":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/"},"wordCount":1214,"publisher":{"@id":"https:\/\/pt.valorhconsultoria.com\/#organization"},"image":{"@id":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/#primaryimage"},"thumbnailUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2019\/01\/METAS-1.jpg","keywords":["Definir metas","metas","metas pessoais e corporativas","motiva\u00e7\u00e3o","sucesso profissional"],"articleSection":["Blog"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/","url":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/","name":"Definir metas \u00e9 um componente fundamental para o sucesso profissional","isPartOf":{"@id":"https:\/\/pt.valorhconsultoria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/#primaryimage"},"image":{"@id":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/#primaryimage"},"thumbnailUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2019\/01\/METAS-1.jpg","datePublished":"2019-01-24T18:27:19+00:00","dateModified":"2020-05-20T22:40:59+00:00","description":"Veja dicas para manter em mente quando voc\u00ea pensar em propor metas, quer sejam elas pessoais ou corporativas","breadcrumb":{"@id":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/#primaryimage","url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2019\/01\/METAS-1.jpg","contentUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2019\/01\/METAS-1.jpg","width":1080,"height":716},{"@type":"BreadcrumbList","@id":"https:\/\/pt.valorhconsultoria.com\/definir-metas-e-um-componente-fundamental-para-o-sucesso-profissional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/pt.valorhconsultoria.com\/"},{"@type":"ListItem","position":2,"name":"Definir metas \u00e9 um componente fundamental para o sucesso profissional"}]},{"@type":"WebSite","@id":"https:\/\/pt.valorhconsultoria.com\/#website","url":"https:\/\/pt.valorhconsultoria.com\/","name":"ValorH","description":"Consultoria e Treinamento","publisher":{"@id":"https:\/\/pt.valorhconsultoria.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pt.valorhconsultoria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/pt.valorhconsultoria.com\/#organization","name":"ValorH Consultoria e Treinamento","url":"https:\/\/pt.valorhconsultoria.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/logo\/image\/","url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2018\/10\/favicon.png","contentUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2018\/10\/favicon.png","width":200,"height":199,"caption":"ValorH Consultoria e Treinamento"},"image":{"@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/valorhconsultoria\/","https:\/\/www.instagram.com\/valorhconsultoria\/","https:\/\/br.linkedin.com\/in\/valorhconsultoria"]},{"@type":"Person","@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/person\/53caa52db0debe9896f35cf99abc3339","name":"valorh","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g","caption":"valorh"}}]}},"_links":{"self":[{"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/posts\/2993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/comments?post=2993"}],"version-history":[{"count":1,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/posts\/2993\/revisions"}],"predecessor-version":[{"id":23208,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/posts\/2993\/revisions\/23208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/media\/2996"}],"wp:attachment":[{"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/media?parent=2993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/categories?post=2993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/tags?post=2993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}