{"id":23988,"date":"2021-09-23T22:38:38","date_gmt":"2021-09-24T01:38:38","guid":{"rendered":"https:\/\/valorhconsultoria.com.br\/?p=23988"},"modified":"2021-09-23T22:39:18","modified_gmt":"2021-09-24T01:39:18","slug":"a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios","status":"publish","type":"post","link":"https:\/\/pt.valorhconsultoria.com\/pt\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/","title":{"rendered":"A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS"},"content":{"rendered":"<p>A pesquisa salarial \u00e9 uma das principais ferramentas do RH de uma empresa, ela serve como base para a tomada de decis\u00f5es muito importantes que podem definir a satisfa\u00e7\u00e3o, perman\u00eancia e atra\u00e7\u00e3o dos melhores talentos do mercado. \u00c9 um meio que o RH utiliza para analisar o cen\u00e1rio da remunera\u00e7\u00e3o dos profissionais no mercado e, dessa forma, manter o equil\u00edbrio interno e externo do seu plano de cargos e sal\u00e1rios.<\/p>\n\n\n\n<p>Ok, entendemos que, de forma resumida, a pesquisa salarial \u00e9 um comparativo da organiza\u00e7\u00e3o com o mercado em termos financeiros, mas, para que essa an\u00e1lise se mostre \u00fatil \u00e9 preciso tomar alguns cuidados na hora de efetu\u00e1-la, por exemplo:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Quantas e quais s\u00e3o as empresas que v\u00e3o entrar na compara\u00e7\u00e3o dessa an\u00e1lise?&nbsp;<ol><li>Elas devem ser do mesmo segmento que voc\u00ea est\u00e1 analisando;<\/li><li>Elas devem ser da mesma regi\u00e3o ou de uma regi\u00e3o geogr\u00e1fica semelhante a sua;<\/li><li>Elas devem ter um porte, uma participa\u00e7\u00e3o de mercado, parecido com o seu;<\/li><li>Elas n\u00e3o devem ser menos do que o que voc\u00ea almeja para a sua empresa, mas tamb\u00e9m n\u00e3o podem ser t\u00e3o mais, porque essa \u00e9 uma pesquisa que vai lhe ajudar no seu cen\u00e1rio atual e que pode, e deve, ser repetida no futuro.<\/li><\/ol><\/li><\/ol>\n\n\n\n<p>DICA: Escolha ao menos 7 empresas para comparar com a sua e foque na qualidade dessa sele\u00e7\u00e3o.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\"><li>Voc\u00ea est\u00e1 analisando a parte financeira, sim, mas n\u00e3o somente. \u00c9 preciso se atentar ao funcionamento do mercado como um todo:<ol><li>Como est\u00e1 a demanda e oferta de trabalho nesse segmento?<\/li><li>Qual o n\u00edvel de valor agregado das pessoas?<\/li><\/ol><\/li><\/ol>\n\n\n\n<p>Perceba que as quest\u00f5es colocadas em (2) possuem respostas vari\u00e1veis dependendo do momento e local em que s\u00e3o feitas, portanto, a pesquisa salarial deve ser feita com certa frequ\u00eancia para que os resultados se mantenham positivos.<\/p>\n\n\n\n<p>Ap\u00f3s entender os crit\u00e9rios m\u00ednimos para reunir os dados necess\u00e1rios para an\u00e1lise, \u00e9 preciso entender como ela \u00e9 feita. Para come\u00e7ar, confira:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Os cargos-chave da organiza\u00e7\u00e3o.<ul><li>Quais s\u00e3o os cargos mais relevantes dentro da sua empresa?<\/li><\/ul><\/li><li>Os objetivos da organiza\u00e7\u00e3o.<ul><li>Qual a vis\u00e3o de futuro da sua empresa? Onde voc\u00ea quer chegar?<\/li><\/ul><\/li><li>Quest\u00f5es internas e externas.<ul><li>Internamente, observe a hierarquia de cargos e suas respectivas remunera\u00e7\u00f5es.<\/li><li>Externamente, observe a participa\u00e7\u00e3o de mercado da empresa, seu tamanho em quantidade de funcion\u00e1rios e em volume de produ\u00e7\u00e3o e faturamento.<\/li><\/ul><\/li><\/ul>\n\n\n\n<p>A pesquisa salarial \u00e9 uma excelente ferramenta de gest\u00e3o de pessoas, desde que realizada com seriedade e aten\u00e7\u00e3o.<\/p>\n\n\n\n<p>Sabendo que a pesquisa salarial serve como base para o desenvolvimento de um bom plano de cargos e sal\u00e1rios e que deve ser feita regularmente, \u00e9 v\u00e1lido dizer que esse tipo de an\u00e1lise pode ser feita pela pr\u00f3pria empresa ou por uma empresa especializada. A forma como essa pesquisa se dar\u00e1 tamb\u00e9m \u00e9 uma decis\u00e3o estrat\u00e9gica e or\u00e7ament\u00e1ria. Se voc\u00ea achar que n\u00e3o tem \u00e0 sua disposi\u00e7\u00e3o uma equipe capaz de fazer essa an\u00e1lise, contrate uma equipe especializada que ir\u00e1 identificar as nuances que n\u00e3o podem passar despercebidas, como: o contexto da cultura organizacional,&nbsp; o sistema de gest\u00e3o de pessoas e muito mais, de forma a comparar tudo isso com o que est\u00e1 no mercado atual e ent\u00e3o propor o melhor plano de cargos e sal\u00e1rios para que a organiza\u00e7\u00e3o prospere.<\/p>\n\n\n\n<p>Achou interessante? Quer ajuda com a pesquisa salarial e determina\u00e7\u00e3o de cargos e sal\u00e1rios na sua empresa? Conte com a ValorH!Acompanhe mais dicas e informa\u00e7\u00f5es exclusivas em nossas redes sociais. Estamos no&nbsp;<a href=\"https:\/\/www.facebook.com\/valorhconsultoria\/\"><strong>Facebook<\/strong><\/a>&nbsp;e&nbsp;<a href=\"https:\/\/www.instagram.com\/valorhconsultoria\/\"><strong>Instagram<\/strong><\/a>!<\/p>","protected":false},"excerpt":{"rendered":"<p>A pesquisa salarial \u00e9 uma das principais ferramentas do RH de uma empresa, ela serve como base para a tomada de decis\u00f5es muito importantes que podem definir a satisfa\u00e7\u00e3o, perman\u00eancia e atra\u00e7\u00e3o dos melhores talentos do mercado. \u00c9 um meio que o RH utiliza para analisar o cen\u00e1rio da remunera\u00e7\u00e3o dos profissionais no mercado e, [&hellip;]<\/p>","protected":false},"author":3,"featured_media":23990,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[],"class_list":["post-23988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS | ValorH<\/title>\n<meta name=\"description\" content=\"A ValorH Consultoria e Treinamentos possui capacidade operacional para atender clientes em todo o territ\u00f3rio nacional com um servi\u00e7o de qualidade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pt.valorhconsultoria.com\/pt\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS | ValorH\" \/>\n<meta property=\"og:description\" content=\"A ValorH Consultoria e Treinamentos possui capacidade operacional para atender clientes em todo o territ\u00f3rio nacional com um servi\u00e7o de qualidade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pt.valorhconsultoria.com\/pt\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/\" \/>\n<meta property=\"og:site_name\" content=\"ValorH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/valorhconsultoria\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-24T01:38:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-24T01:39:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/09\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"911\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"valorh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"valorh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/\"},\"author\":{\"name\":\"valorh\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/person\\\/53caa52db0debe9896f35cf99abc3339\"},\"headline\":\"A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS\",\"datePublished\":\"2021-09-24T01:38:38+00:00\",\"dateModified\":\"2021-09-24T01:39:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/\"},\"wordCount\":640,\"publisher\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/\",\"name\":\"A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS | ValorH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios.jpg\",\"datePublished\":\"2021-09-24T01:38:38+00:00\",\"dateModified\":\"2021-09-24T01:39:18+00:00\",\"description\":\"A ValorH Consultoria e Treinamentos possui capacidade operacional para atender clientes em todo o territ\u00f3rio nacional com um servi\u00e7o de qualidade.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios.jpg\",\"contentUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios.jpg\",\"width\":1366,\"height\":911},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#website\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\",\"name\":\"ValorH\",\"description\":\"Consultoria e Treinamento\",\"publisher\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\",\"name\":\"ValorH Consultoria e Treinamento\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/favicon.png\",\"width\":200,\"height\":199,\"caption\":\"ValorH Consultoria e Treinamento\"},\"image\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/valorhconsultoria\\\/\",\"https:\\\/\\\/www.instagram.com\\\/valorhconsultoria\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/in\\\/valorhconsultoria\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/person\\\/53caa52db0debe9896f35cf99abc3339\",\"name\":\"valorh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g\",\"caption\":\"valorh\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS | ValorH","description":"A ValorH Consultoria e Treinamentos possui capacidade operacional para atender clientes em todo o territ\u00f3rio nacional com um servi\u00e7o de qualidade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pt.valorhconsultoria.com\/pt\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/","og_locale":"pt_PT","og_type":"article","og_title":"A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS | ValorH","og_description":"A ValorH Consultoria e Treinamentos possui capacidade operacional para atender clientes em todo o territ\u00f3rio nacional com um servi\u00e7o de qualidade.","og_url":"https:\/\/pt.valorhconsultoria.com\/pt\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/","og_site_name":"ValorH","article_publisher":"https:\/\/www.facebook.com\/valorhconsultoria\/","article_published_time":"2021-09-24T01:38:38+00:00","article_modified_time":"2021-09-24T01:39:18+00:00","og_image":[{"width":1366,"height":911,"url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/09\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios.jpg","type":"image\/jpeg"}],"author":"valorh","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"valorh","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/#article","isPartOf":{"@id":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/"},"author":{"name":"valorh","@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/person\/53caa52db0debe9896f35cf99abc3339"},"headline":"A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS","datePublished":"2021-09-24T01:38:38+00:00","dateModified":"2021-09-24T01:39:18+00:00","mainEntityOfPage":{"@id":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/"},"wordCount":640,"publisher":{"@id":"https:\/\/pt.valorhconsultoria.com\/#organization"},"image":{"@id":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/#primaryimage"},"thumbnailUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/09\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios.jpg","articleSection":["Blog"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/","url":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/","name":"A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS | ValorH","isPartOf":{"@id":"https:\/\/pt.valorhconsultoria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/#primaryimage"},"image":{"@id":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/#primaryimage"},"thumbnailUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/09\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios.jpg","datePublished":"2021-09-24T01:38:38+00:00","dateModified":"2021-09-24T01:39:18+00:00","description":"A ValorH Consultoria e Treinamentos possui capacidade operacional para atender clientes em todo o territ\u00f3rio nacional com um servi\u00e7o de qualidade.","breadcrumb":{"@id":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/#primaryimage","url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/09\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios.jpg","contentUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/09\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios.jpg","width":1366,"height":911},{"@type":"BreadcrumbList","@id":"https:\/\/pt.valorhconsultoria.com\/a-importancia-da-pesquisa-salarial-para-o-plano-de-cargos-e-salarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/pt.valorhconsultoria.com\/"},{"@type":"ListItem","position":2,"name":"A IMPORT\u00c2NCIA DA PESQUISA SALARIAL PARA O PLANO DE CARGOS E SAL\u00c1RIOS"}]},{"@type":"WebSite","@id":"https:\/\/pt.valorhconsultoria.com\/#website","url":"https:\/\/pt.valorhconsultoria.com\/","name":"ValorH","description":"Consultoria e Treinamento","publisher":{"@id":"https:\/\/pt.valorhconsultoria.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pt.valorhconsultoria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/pt.valorhconsultoria.com\/#organization","name":"ValorH Consultoria e Treinamento","url":"https:\/\/pt.valorhconsultoria.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/logo\/image\/","url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2018\/10\/favicon.png","contentUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2018\/10\/favicon.png","width":200,"height":199,"caption":"ValorH Consultoria e Treinamento"},"image":{"@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/valorhconsultoria\/","https:\/\/www.instagram.com\/valorhconsultoria\/","https:\/\/br.linkedin.com\/in\/valorhconsultoria"]},{"@type":"Person","@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/person\/53caa52db0debe9896f35cf99abc3339","name":"valorh","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g","caption":"valorh"}}]}},"_links":{"self":[{"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/posts\/23988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/comments?post=23988"}],"version-history":[{"count":1,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/posts\/23988\/revisions"}],"predecessor-version":[{"id":23989,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/posts\/23988\/revisions\/23989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/media\/23990"}],"wp:attachment":[{"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/media?parent=23988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/categories?post=23988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/pt\/wp-json\/wp\/v2\/tags?post=23988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}