{"id":24010,"date":"2021-10-21T13:11:46","date_gmt":"2021-10-21T16:11:46","guid":{"rendered":"https:\/\/valorhconsultoria.com.br\/?p=24010"},"modified":"2021-10-21T13:14:54","modified_gmt":"2021-10-21T16:14:54","slug":"como-desenvolver-inteligencia-emocional-nas-equipes","status":"publish","type":"post","link":"https:\/\/pt.valorhconsultoria.com\/es\/como-desenvolver-inteligencia-emocional-nas-equipes\/","title":{"rendered":"C\u00d3MO DESARROLLAR LA INTELIGENCIA EMOCIONAL EN LOS EQUIPOS"},"content":{"rendered":"<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL-1024x682.jpg\" alt=\"\" class=\"wp-image-24011\" srcset=\"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL-1024x682.jpg 1024w, https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL-330x220.jpg 330w, https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL-768x512.jpg 768w, https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL.jpg 1055w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>Una de las habilidades m\u00e1s importantes en el mundo empresarial es saber c\u00f3mo tratar con las personas y las situaciones adversas con inteligencia. Para lograrlo, es fundamental contar con lo que conocemos como inteligencia emocional. La inteligencia emocional es importante no solo para los profesionales de RR. HH., sino para todo el equipo de la empresa.<\/p>\n\n\n\n<p>En el post de hoy aclararemos qu\u00e9 es la inteligencia emocional y c\u00f3mo funciona dentro de una organizaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQU\u00c9 ES LA INTELIGENCIA EMOCIONAL?<\/h2>\n\n\n\n<p>La inteligencia emocional es la capacidad de identificar los propios sentimientos y los de los dem\u00e1s, y de gestionarlos sin dejarse llevar. Es algo necesario en todos los \u00e1mbitos de la vida, y en el trabajo no es la excepci\u00f3n, ya que es necesario tener un buen estado psicol\u00f3gico para afrontar plazos, presiones, conflictos, diferentes personas, etc.<\/p>\n\n\n\n<p>Quiz\u00e1s hayas o\u00eddo que se contrata a las personas por sus habilidades t\u00e9cnicas, pero se las despide por su comportamiento, \u00bfverdad? Esta afirmaci\u00f3n no es nueva, pero nunca ha sido tan relevante. Hoy en d\u00eda, con el avance de la tecnolog\u00eda, varios aspectos t\u00e9cnicos est\u00e1n siendo reemplazados por la inteligencia artificial y las m\u00e1quinas, por lo que la habilidad que ha cobrado mayor relevancia en las empresas es la inteligencia emocional, la soft skill m\u00e1s importante hoy en d\u00eda para quienes desean progresar en sus carreras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCU\u00c1LES SON LAS CARACTER\u00cdSTICAS DE LAS PERSONAS CON INTELIGENCIA EMOCIONAL?<\/h2>\n\n\n\n<p>Una de las principales caracter\u00edsticas de una persona con inteligencia emocional es el autoconocimiento, es decir, saber cu\u00e1les son sus fortalezas, debilidades y l\u00edmites. Esta conciencia es esencial porque le permite utilizar sus fortalezas y buscar aprovechar sus debilidades estrat\u00e9gicamente.<\/p>\n\n\n\n<p>El control emocional tambi\u00e9n es una caracter\u00edstica que merece ser destacada. Saber identificar las emociones, comprenderlas y mantener la calma en cualquier situaci\u00f3n ayuda a evitar que los problemas se agraven, facilitando adem\u00e1s su resoluci\u00f3n.<\/p>\n\n\n\n<p>La inteligencia emocional tambi\u00e9n es importante porque contribuye a la buena convivencia entre las personas, evitando conflictos y manteniendo el equilibrio dentro del equipo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCU\u00c1LES SON LOS CONFLICTOS M\u00c1S COMUNES DENTRO DE LAS EMPRESAS?<\/h2>\n\n\n\n<p>Los conflictos m\u00e1s comunes dentro de las empresas tienen que ver con las relaciones interpersonales: directivos agresivos, casos de insubordinaci\u00f3n, desacuerdos entre empleados, falta de cooperaci\u00f3n dentro de los equipos\u2026 Todos estos conflictos se producen principalmente por la falta de inteligencia emocional de las personas.<\/p>\n\n\n\n<p>El primer paso para salir de estas situaciones pac\u00edficamente es empatizar con la otra persona, cambiar de perspectiva e intentar comprender su situaci\u00f3n y por qu\u00e9 se comporta as\u00ed. Este peque\u00f1o gesto puede cambiar por completo el curso de una situaci\u00f3n que podr\u00eda derivar en conflicto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00d3MO DESARROLLAR LA INTELIGENCIA EMOCIONAL EN EL EQUIPO?<\/h2>\n\n\n\n<p>Existen varios m\u00e9todos para desarrollar la inteligencia emocional en tu equipo, y puedes usar m\u00e1s de uno. Puedes ofrecer a los empleados formaci\u00f3n especializada en inteligencia emocional, promover actividades divertidas para fortalecer los v\u00ednculos entre ellos y como equipo, brindar retroalimentaci\u00f3n regular de forma respetuosa e individual, y contar con ayuda especializada para identificar la necesidad de inteligencia personal y c\u00f3mo abordarla dentro de la organizaci\u00f3n.<br>Sigue m\u00e1s consejos e informaci\u00f3n exclusiva en nuestras redes sociales. estamos en&nbsp;<a href=\"https:\/\/www.facebook.com\/valorhconsultoria\/\"><strong>Facebook<\/strong><\/a>&nbsp;y&nbsp;<a href=\"https:\/\/www.instagram.com\/valorhconsultoria\/\"><strong>Instagram<\/strong><\/a>!<\/p>","protected":false},"excerpt":{"rendered":"<p>Una de las habilidades esenciales en el mundo empresarial es saber c\u00f3mo tratar con las personas y las situaciones adversas con inteligencia; para ello, es fundamental contar con lo que conocemos como inteligencia emocional. La inteligencia emocional es importante no solo para los profesionales de RR. HH., sino para todo el equipo de la empresa. En el puesto de [\u2026]<\/p>","protected":false},"author":3,"featured_media":24011,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[],"class_list":["post-24010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMO DESENVOLVER INTELIG\u00caNCIA EMOCIONAL NAS EQUIPES | ValorH<\/title>\n<meta name=\"description\" content=\"A ValorH Consultoria e Treinamentos possui capacidade operacional para atender clientes em todo o territ\u00f3rio nacional com um servi\u00e7o de qualidade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pt.valorhconsultoria.com\/es\/como-desenvolver-inteligencia-emocional-nas-equipes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMO DESENVOLVER INTELIG\u00caNCIA EMOCIONAL NAS EQUIPES | ValorH\" \/>\n<meta property=\"og:description\" content=\"A ValorH Consultoria e Treinamentos possui capacidade operacional para atender clientes em todo o territ\u00f3rio nacional com um servi\u00e7o de qualidade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pt.valorhconsultoria.com\/es\/como-desenvolver-inteligencia-emocional-nas-equipes\/\" \/>\n<meta property=\"og:site_name\" content=\"ValorH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/valorhconsultoria\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-21T16:11:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-21T16:14:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1055\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"valorh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"valorh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/\"},\"author\":{\"name\":\"valorh\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/person\\\/53caa52db0debe9896f35cf99abc3339\"},\"headline\":\"COMO DESENVOLVER INTELIG\u00caNCIA EMOCIONAL NAS EQUIPES\",\"datePublished\":\"2021-10-21T16:11:46+00:00\",\"dateModified\":\"2021-10-21T16:14:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/\"},\"wordCount\":586,\"publisher\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/INTELIGeNCIA-EMOCIONAL.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/\",\"name\":\"COMO DESENVOLVER INTELIG\u00caNCIA EMOCIONAL NAS EQUIPES | ValorH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/INTELIGeNCIA-EMOCIONAL.jpg\",\"datePublished\":\"2021-10-21T16:11:46+00:00\",\"dateModified\":\"2021-10-21T16:14:54+00:00\",\"description\":\"A ValorH Consultoria e Treinamentos possui capacidade operacional para atender clientes em todo o territ\u00f3rio nacional com um servi\u00e7o de qualidade.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/INTELIGeNCIA-EMOCIONAL.jpg\",\"contentUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/INTELIGeNCIA-EMOCIONAL.jpg\",\"width\":1055,\"height\":703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/como-desenvolver-inteligencia-emocional-nas-equipes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMO DESENVOLVER INTELIG\u00caNCIA EMOCIONAL NAS EQUIPES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#website\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\",\"name\":\"ValorH\",\"description\":\"Consultoria e Treinamento\",\"publisher\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\",\"name\":\"ValorH Consultoria e Treinamento\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/favicon.png\",\"width\":200,\"height\":199,\"caption\":\"ValorH Consultoria e Treinamento\"},\"image\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/valorhconsultoria\\\/\",\"https:\\\/\\\/www.instagram.com\\\/valorhconsultoria\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/in\\\/valorhconsultoria\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/person\\\/53caa52db0debe9896f35cf99abc3339\",\"name\":\"valorh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g\",\"caption\":\"valorh\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo desarrollar la inteligencia emocional en equipos | ValorH","description":"ValorH Consultoria e Treinamentos tiene la capacidad operativa para atender a clientes en todo el pa\u00eds con un servicio de calidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pt.valorhconsultoria.com\/es\/como-desenvolver-inteligencia-emocional-nas-equipes\/","og_locale":"es_ES","og_type":"article","og_title":"COMO DESENVOLVER INTELIG\u00caNCIA EMOCIONAL NAS EQUIPES | ValorH","og_description":"A ValorH Consultoria e Treinamentos possui capacidade operacional para atender clientes em todo o territ\u00f3rio nacional com um servi\u00e7o de qualidade.","og_url":"https:\/\/pt.valorhconsultoria.com\/es\/como-desenvolver-inteligencia-emocional-nas-equipes\/","og_site_name":"ValorH","article_publisher":"https:\/\/www.facebook.com\/valorhconsultoria\/","article_published_time":"2021-10-21T16:11:46+00:00","article_modified_time":"2021-10-21T16:14:54+00:00","og_image":[{"width":1055,"height":703,"url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL.jpg","type":"image\/jpeg"}],"author":"valorh","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"valorh","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/#article","isPartOf":{"@id":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/"},"author":{"name":"valorh","@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/person\/53caa52db0debe9896f35cf99abc3339"},"headline":"COMO DESENVOLVER INTELIG\u00caNCIA EMOCIONAL NAS EQUIPES","datePublished":"2021-10-21T16:11:46+00:00","dateModified":"2021-10-21T16:14:54+00:00","mainEntityOfPage":{"@id":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/"},"wordCount":586,"publisher":{"@id":"https:\/\/pt.valorhconsultoria.com\/#organization"},"image":{"@id":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/#primaryimage"},"thumbnailUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL.jpg","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/","url":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/","name":"C\u00f3mo desarrollar la inteligencia emocional en equipos | ValorH","isPartOf":{"@id":"https:\/\/pt.valorhconsultoria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/#primaryimage"},"image":{"@id":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/#primaryimage"},"thumbnailUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL.jpg","datePublished":"2021-10-21T16:11:46+00:00","dateModified":"2021-10-21T16:14:54+00:00","description":"ValorH Consultoria e Treinamentos tiene la capacidad operativa para atender a clientes en todo el pa\u00eds con un servicio de calidad.","breadcrumb":{"@id":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/#primaryimage","url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL.jpg","contentUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2021\/10\/INTELIGeNCIA-EMOCIONAL.jpg","width":1055,"height":703},{"@type":"BreadcrumbList","@id":"https:\/\/pt.valorhconsultoria.com\/como-desenvolver-inteligencia-emocional-nas-equipes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/pt.valorhconsultoria.com\/"},{"@type":"ListItem","position":2,"name":"COMO DESENVOLVER INTELIG\u00caNCIA EMOCIONAL NAS EQUIPES"}]},{"@type":"WebSite","@id":"https:\/\/pt.valorhconsultoria.com\/#website","url":"https:\/\/pt.valorhconsultoria.com\/","name":"ValorH","description":"Consultor\u00eda y Capacitaci\u00f3n","publisher":{"@id":"https:\/\/pt.valorhconsultoria.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pt.valorhconsultoria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pt.valorhconsultoria.com\/#organization","name":"ValorH Consultor\u00eda y Formaci\u00f3n","url":"https:\/\/pt.valorhconsultoria.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/logo\/image\/","url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2018\/10\/favicon.png","contentUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2018\/10\/favicon.png","width":200,"height":199,"caption":"ValorH Consultoria e Treinamento"},"image":{"@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/valorhconsultoria\/","https:\/\/www.instagram.com\/valorhconsultoria\/","https:\/\/br.linkedin.com\/in\/valorhconsultoria"]},{"@type":"Person","@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/person\/53caa52db0debe9896f35cf99abc3339","name":"valor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4501b3fe0983bec8b0a236f90c9b2b26f463bf99e8d13bfcd68dd93df1345f70?s=96&d=mm&r=g","caption":"valorh"}}]}},"_links":{"self":[{"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/posts\/24010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/comments?post=24010"}],"version-history":[{"count":2,"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/posts\/24010\/revisions"}],"predecessor-version":[{"id":24013,"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/posts\/24010\/revisions\/24013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/media\/24011"}],"wp:attachment":[{"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/media?parent=24010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/categories?post=24010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/tags?post=24010"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}