{"id":1284,"count":1,"description":"","link":"https:\/\/pt.valorhconsultoria.com\/es\/category\/cargos-e-salarios\/","name":"puestos y salarios","slug":"cargos-e-salarios","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>cargos e sal\u00e1rios | ValorH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pt.valorhconsultoria.com\/es\/category\/cargos-e-salarios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cargos e sal\u00e1rios | ValorH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pt.valorhconsultoria.com\/es\/category\/cargos-e-salarios\/\" \/>\n<meta property=\"og:site_name\" content=\"ValorH\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2018\/09\/blank-img.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/category\\\/cargos-e-salarios\\\/\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/category\\\/cargos-e-salarios\\\/\",\"name\":\"cargos e sal\u00e1rios | ValorH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/category\\\/cargos-e-salarios\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/category\\\/cargos-e-salarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cargos e sal\u00e1rios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#website\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\",\"name\":\"ValorH\",\"description\":\"Consultoria e Treinamento\",\"publisher\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#organization\",\"name\":\"ValorH Consultoria e Treinamento\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/favicon.png\",\"width\":200,\"height\":199,\"caption\":\"ValorH Consultoria e Treinamento\"},\"image\":{\"@id\":\"https:\\\/\\\/pt.valorhconsultoria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/valorhconsultoria\\\/\",\"https:\\\/\\\/www.instagram.com\\\/valorhconsultoria\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/in\\\/valorhconsultoria\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"cargos e sal\u00e1rios | ValorH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pt.valorhconsultoria.com\/es\/category\/cargos-e-salarios\/","og_locale":"es_ES","og_type":"article","og_title":"cargos e sal\u00e1rios | ValorH","og_url":"https:\/\/pt.valorhconsultoria.com\/es\/category\/cargos-e-salarios\/","og_site_name":"ValorH","og_image":[{"width":1280,"height":853,"url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2018\/09\/blank-img.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pt.valorhconsultoria.com\/category\/cargos-e-salarios\/","url":"https:\/\/pt.valorhconsultoria.com\/category\/cargos-e-salarios\/","name":"cargos e sal\u00e1rios | ValorH","isPartOf":{"@id":"https:\/\/pt.valorhconsultoria.com\/#website"},"breadcrumb":{"@id":"https:\/\/pt.valorhconsultoria.com\/category\/cargos-e-salarios\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/pt.valorhconsultoria.com\/category\/cargos-e-salarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/pt.valorhconsultoria.com\/"},{"@type":"ListItem","position":2,"name":"cargos e sal\u00e1rios"}]},{"@type":"WebSite","@id":"https:\/\/pt.valorhconsultoria.com\/#website","url":"https:\/\/pt.valorhconsultoria.com\/","name":"ValorH","description":"Consultor\u00eda y Capacitaci\u00f3n","publisher":{"@id":"https:\/\/pt.valorhconsultoria.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pt.valorhconsultoria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pt.valorhconsultoria.com\/#organization","name":"ValorH Consultor\u00eda y Formaci\u00f3n","url":"https:\/\/pt.valorhconsultoria.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/logo\/image\/","url":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2018\/10\/favicon.png","contentUrl":"https:\/\/pt.valorhconsultoria.com\/wp-content\/uploads\/2018\/10\/favicon.png","width":200,"height":199,"caption":"ValorH Consultoria e Treinamento"},"image":{"@id":"https:\/\/pt.valorhconsultoria.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/valorhconsultoria\/","https:\/\/www.instagram.com\/valorhconsultoria\/","https:\/\/br.linkedin.com\/in\/valorhconsultoria"]}]}},"_links":{"self":[{"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/categories\/1284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/pt.valorhconsultoria.com\/es\/wp-json\/wp\/v2\/posts?categories=1284"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}